{"id":531,"date":"2026-07-21T18:29:21","date_gmt":"2026-07-21T18:29:21","guid":{"rendered":"https:\/\/mypa.gatheomix.com\/?page_id=531"},"modified":"2026-08-27T15:56:29","modified_gmt":"2026-08-27T15:56:29","slug":"contactos","status":"publish","type":"page","link":"https:\/\/mypa.gatheomix.com\/en\/contactos\/","title":{"rendered":"Contacts"},"content":{"rendered":"\n\t\t<div id=\"fws_6a987f28b1624\"  data-column-margin=\"default\" data-midnight=\"light\"  class=\"wpb_row vc_row-fluid vc_row full-width-content bg-animation--slight vc_row-o-equal-height vc_row-flex vc_row-o-content-middle  zindex-set height_desktop_510px right_padding_tablet_40px right_padding_phone_40px left_padding_tablet_40px left_padding_phone_40px\"  style=\"padding-top: 0px; padding-bottom: 0px;  z-index: 999;\"><div class=\"row-bg-wrap\" data-bg-animation=\"zoom-out-reveal\" data-bg-animation-delay=\"\" data-bg-overlay=\"false\"><div class=\"inner-wrap row-bg-layer using-image\" ><div class=\"row-bg viewport-desktop using-image\"  style=\"background-image: url(https:\/\/mypa.gatheomix.com\/wp-content\/uploads\/2026\/07\/Group-871-1.webp); background-position: center center; background-repeat: no-repeat; \"><\/div><\/div><\/div><div class=\"row_col_wrap_12 col span_12 light center\">\n\t<div  class=\"vc_col-sm-12 wpb_column column_container vc_column_container col no-extra-padding inherit_tablet inherit_phone flex_gap_desktop_10px \"  data-padding-pos=\"all\" data-has-bg-color=\"false\" data-bg-color=\"\" data-bg-opacity=\"1\" data-animation=\"\" data-delay=\"0\" >\n\t\t<div class=\"vc_column-inner\" >\n\t\t\t<div class=\"wpb_wrapper\">\n\t\t\t\t\n<div class=\"wpb_text_column wpb_content_element  wpb_animate_when_almost_visible wpb_fadeInDown fadeInDown vc_custom_1784658345002\"  id=\"icon-stop-porque\">\n\t<p><i class=\"fa fa-stop\"><\/i>\u00a0 CONTACTO<\/p>\n<\/div>\n\n\n\n<div class=\"nectar-split-heading  font_size_48px font_size_phone_43px \" data-align=\"center\" data-m-align=\"inherit\" data-text-effect=\"letter-reveal-blur-top\" data-animation-type=\"line-reveal-by-space\" data-animation-delay=\"500\" data-animation-offset=\"\" data-m-rm-animation=\"\" data-stagger=\"\" data-custom-font-size=\"true\" style=\"font-size: 48px; line-height: 51.84px;\"><h3 style=\"max-width: 600px;\">Vamos transformar o seu projeto?<\/h3><\/div>\n\t\t\t<\/div> \n\t\t<\/div>\n\t<\/div> \n<\/div><\/div>\n\t\t<div id=\"fws_6a987f28b18b9\"  data-column-margin=\"default\" data-midnight=\"dark\"  class=\"wpb_row vc_row-fluid vc_row full-width-section  zindex-set\"  style=\"padding-top: 0px; padding-bottom: 0px;  z-index: 999;\"><div class=\"row-bg-wrap\" data-bg-animation=\"none\" data-bg-animation-delay=\"\" data-bg-overlay=\"false\"><div class=\"inner-wrap row-bg-layer\" ><div class=\"row-bg viewport-desktop\"  style=\"\"><\/div><\/div><\/div><div class=\"row_col_wrap_12 col span_12 dark left\">\n\t<div  class=\"vc_col-sm-12 wpb_column column_container vc_column_container col no-extra-padding inherit_tablet inherit_phone flex_gap_desktop_10px \"  data-padding-pos=\"all\" data-has-bg-color=\"false\" data-bg-color=\"\" data-bg-opacity=\"1\" data-animation=\"\" data-delay=\"0\" >\n\t\t<div class=\"vc_column-inner\" >\n\t\t\t<div class=\"wpb_wrapper\">\n\t\t\t\t<div class=\"img-with-aniamtion-wrap right custom-width-146px position_desktop_absolute top_position_desktop_0px right_position_desktop_0px translate_y_desktop_-120px z_index_999 \" data-max-width=\"custom\" data-max-width-mobile=\"default\" data-shadow=\"none\" data-animation=\"none\" >\n      <div class=\"inner\">\n        <div class=\"hover-wrap\"> \n          <div class=\"hover-wrap-inner\">\n            <img loading=\"lazy\" decoding=\"async\" class=\"img-with-animation skip-lazy\" data-delay=\"0\" height=\"191\" width=\"146\" data-animation=\"none\" src=\"https:\/\/mypa.gatheomix.com\/wp-content\/uploads\/2026\/07\/Vector-6.png\" alt=\"\"  \/>\n          <\/div>\n        <\/div>\n        \n      <\/div>\n    <\/div>\n\t\t\t<\/div> \n\t\t<\/div>\n\t<\/div> \n<\/div><\/div>\n\t\t<div id=\"fws_6a987f28b1b38\"  data-column-margin=\"default\" data-midnight=\"dark\"  class=\"wpb_row vc_row-fluid vc_row full-width-section has-row-bg-color  bottom_padding_phone_60px\"  style=\"padding-top: 25px; padding-bottom: 80px; --row-bg-color: #FAF9F6;\"><div class=\"row-bg-wrap\" data-bg-animation=\"none\" data-bg-animation-delay=\"\" data-bg-overlay=\"false\"><div class=\"inner-wrap row-bg-layer\" ><div class=\"row-bg viewport-desktop using-bg-color\"  style=\"background-color: #FAF9F6; \"><\/div><\/div><\/div><div class=\"row_col_wrap_12 col span_12 dark left\">\n\t<div  class=\"vc_col-sm-12 wpb_column column_container vc_column_container col no-extra-padding inherit_tablet inherit_phone flex_gap_desktop_10px \"  data-padding-pos=\"all\" data-has-bg-color=\"false\" data-bg-color=\"\" data-bg-opacity=\"1\" data-animation=\"\" data-delay=\"0\" >\n\t\t<div class=\"vc_column-inner\" >\n\t\t\t<div class=\"wpb_wrapper\">\n\t\t\t\t<div class=\"divider-wrap\" data-alignment=\"default\"><div style=\"margin-top: 12.5px; height: 1px; margin-bottom: 12.5px;\" data-width=\"100%\" data-animate=\"yes\" data-animation-delay=\"600\" data-color=\"default\" class=\"divider-border\"><\/div><\/div><div id=\"fws_6a987f28b1c51\" data-midnight=\"\" data-column-margin=\"custom\" class=\"wpb_row vc_row-fluid vc_row inner_row  column-margin-8pct\"  style=\"padding-top: 60px; padding-bottom: 50px; \"><div class=\"row-bg-wrap\"> <div class=\"row-bg\" ><\/div> <\/div><div class=\"row_col_wrap_12_inner col span_12  left\">\n\t<div  class=\"vc_col-sm-6 wpb_column column_container vc_column_container col child_column no-extra-padding force-desktop-text-align-left inherit_tablet inherit_phone flex_layout_desktop_column flex_justify_content_desktop_space-between flex_align_items_desktop_flex-start flex_wrap_desktop_wrap flex_reverse_desktop_false flex_gap_desktop_10px \"   data-padding-pos=\"all\" data-has-bg-color=\"false\" data-bg-color=\"\" data-bg-opacity=\"1\" data-animation=\"\" data-delay=\"0\" >\n\t\t<div class=\"vc_column-inner\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<div class=\"nectar-split-heading  font_size_36px \" data-align=\"left\" data-m-align=\"inherit\" data-text-effect=\"default\" data-animation-type=\"line-reveal-by-space\" data-animation-delay=\"500\" data-animation-offset=\"\" data-m-rm-animation=\"\" data-stagger=\"\" data-custom-font-size=\"true\" style=\"font-size: 36px; line-height: 38.88px;\"><h3 style=\"max-width: 686px;\">Fale connosco para discutir o seu projeto, explorar solu\u00e7\u00f5es ou avaliar oportunidades de colabora\u00e7\u00e3o.<\/h3><\/div>\n\t\t<\/div> \n\t<\/div>\n\t<\/div> \n\n\t<div style=\"margin-top: 10px; \" class=\"vc_col-sm-6 wpb_column column_container vc_column_container col child_column no-extra-padding force-desktop-text-align-left inherit_tablet inherit_phone \"   data-padding-pos=\"all\" data-has-bg-color=\"false\" data-bg-color=\"\" data-bg-opacity=\"1\" data-animation=\"\" data-delay=\"0\" >\n\t\t<div class=\"vc_column-inner\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t\n<div class=\"wpb_text_column wpb_content_element  wpb_animate_when_almost_visible wpb_fadeInUp fadeInUp vc_custom_1784658552516 delay-1000\" style=\" max-width: 436px; display: inline-block;\">\n\t<p>Na MYPA, trabalhamos com arquitetos, construtores, promotores e parceiros para desenvolver solu\u00e7\u00f5es t\u00e9cnicas que tornam projetos ambiciosos poss\u00edveis.<\/p>\n<p>Se tem um desafio, n\u00f3s ajudamos a estruturar a solu\u00e7\u00e3o.<\/p>\n<\/div>\n\n\n\n\n\t\t<\/div> \n\t<\/div>\n\t<\/div> \n<\/div><\/div>\n\t\t\t<\/div> \n\t\t<\/div>\n\t<\/div> \n<\/div><\/div>\n\t\t<div id=\"fws_6a987f28b1e67\"  data-column-margin=\"default\" data-midnight=\"light\"  class=\"wpb_row vc_row-fluid vc_row full-width-section has-row-bg-color\"  style=\"padding-top: 80px; padding-bottom: 80px; --row-bg-color: #1C1C1C;\"><div class=\"row-bg-wrap\" data-bg-animation=\"none\" data-bg-animation-delay=\"\" data-bg-overlay=\"false\"><div class=\"inner-wrap row-bg-layer\" ><div class=\"row-bg viewport-desktop using-bg-color\"  style=\"background-color: #1C1C1C; \"><\/div><\/div><\/div><div class=\"row_col_wrap_12 col span_12 light left\">\n\t<div  class=\"vc_col-sm-2\/5 wpb_column column_container vc_column_container col nectar-sticky-column-css no-extra-padding inherit_tablet inherit_phone \"  data-padding-pos=\"all\" data-has-bg-color=\"false\" data-bg-color=\"\" data-bg-opacity=\"1\" data-animation=\"\" data-delay=\"0\" >\n\t\t<div class=\"n-sticky\"><div class=\"vc_column-inner\" >\n\t\t\t<div class=\"wpb_wrapper\">\n\t\t\t\t<div class=\"nectar-split-heading  font_size_90px \" data-align=\"default\" data-m-align=\"inherit\" data-text-effect=\"letter-reveal-top\" data-animation-type=\"line-reveal-by-space\" data-animation-delay=\"0\" data-animation-offset=\"\" data-m-rm-animation=\"\" data-stagger=\"\" data-custom-font-size=\"true\" style=\"font-size: 90px; line-height: 97.2px;\"><h1 style=\" color: #FAC424;\">Fale com a MYPA<\/h1><\/div>\n\t\t\t<\/div> \n\t\t<\/div><\/div>\n\t<\/div> \n\n\t<div  class=\"vc_col-sm-3\/5 wpb_column column_container vc_column_container col has-animation no-extra-padding inherit_tablet inherit_phone \"  data-padding-pos=\"all\" data-has-bg-color=\"false\" data-bg-color=\"\" data-bg-opacity=\"1\" data-animation=\"fade-in-from-left\" data-delay=\"0\" data-animation-offset=\"70%\" >\n\t\t<div class=\"vc_column-inner\" >\n\t\t\t<div class=\"wpb_wrapper\">\n\t\t\t\t\n\t<div class=\"wpb_raw_code wpb_raw_html wpb_content_element\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<link rel='stylesheet' id='formidable-css' href='https:\/\/mypa.gatheomix.com\/wp-content\/plugins\/formidable\/css\/formidableforms.css?ver=8211616' media='all' \/>\n<div class=\"frm_forms  with_frm_style frm_style_formidable-style\" id=\"frm_form_1_container\" >\n<form enctype=\"multipart\/form-data\" method=\"post\" class=\"frm-show-form  frm_ajax_submit \" id=\"form_contact-form\" >\n<div class=\"frm_form_fields \">\n<fieldset>\n<legend class=\"frm_screen_reader\">Contacte-nos<\/legend>\r\n\r\n<div class=\"frm_fields_container\">\n<input type=\"hidden\" name=\"frm_action\" value=\"create\" \/>\n<input type=\"hidden\" name=\"form_id\" value=\"1\" \/>\n<input type=\"hidden\" name=\"frm_hide_fields_1\" id=\"frm_hide_fields_1\" value=\"\" \/>\n<input type=\"hidden\" name=\"form_key\" value=\"contact-form\" \/>\n<input type=\"hidden\" name=\"item_meta[0]\" value=\"\" \/>\n<input type=\"hidden\" id=\"frm_submit_entry_1\" name=\"frm_submit_entry_1\" value=\"bfe74881dc\" \/><input type=\"hidden\" name=\"_wp_http_referer\" value=\"\/en\/wp-json\/wp\/v2\/pages\/531\" \/><div id=\"frm_field_1_container\" class=\"frm_form_field form-field  frm_inside_container frm_first frm_half\">\r\n\t<label for=\"field_qh4icy\" id=\"field_qh4icy_label\" class=\"frm_primary_label\">Nome\r\n\t\t<span class=\"frm_required\" aria-hidden=\"true\"><\/span>\r\n\t<\/label>\r\n\t<input type=\"text\" id=\"field_qh4icy\" name=\"item_meta[1]\" value=\"\"  data-invmsg=\"Nome is invalid\" aria-invalid=\"false\"  \/>\r\n\t\r\n\t\r\n<\/div>\n<div id=\"frm_field_2_container\" class=\"frm_form_field form-field  frm_inside_container frm_half\">\r\n\t<label for=\"field_ocfup1\" id=\"field_ocfup1_label\" class=\"frm_primary_label\">Empresa\r\n\t\t<span class=\"frm_required\" aria-hidden=\"true\"><\/span>\r\n\t<\/label>\r\n\t<input type=\"text\" id=\"field_ocfup1\" name=\"item_meta[2]\" value=\"\"  data-invmsg=\"Empresa is invalid\" aria-invalid=\"false\"  \/>\r\n\t\r\n\t\r\n<\/div>\n<div id=\"frm_field_3_container\" class=\"frm_form_field form-field  frm_inside_container frm6 frm6 frm_first\">\r\n\t<label for=\"field_29yf4d\" id=\"field_29yf4d_label\" class=\"frm_primary_label\">Email\r\n\t\t<span class=\"frm_required\" aria-hidden=\"true\"><\/span>\r\n\t<\/label>\r\n\t<input type=\"email\" id=\"field_29yf4d\" name=\"item_meta[3]\" value=\"\"  data-invmsg=\"Please enter a valid email address\" aria-invalid=\"false\"  \/>\r\n\t\r\n\t\r\n<\/div>\n<div id=\"frm_field_7_container\" class=\"frm_form_field form-field  frm_inside_container frm6\">\r\n\t<label for=\"field_pegta\" id=\"field_pegta_label\" class=\"frm_primary_label\">Contacto telef\u00f3nico\r\n\t\t<span class=\"frm_required\" aria-hidden=\"true\"><\/span>\r\n\t<\/label>\r\n\t<input type=\"tel\" id=\"field_pegta\" name=\"item_meta[7]\" value=\"\"  data-invmsg=\"Contacto telef\u00f3nico is invalid\" aria-invalid=\"false\" pattern=\"((\\+\\d{1,3}(-|.| )?\\(?\\d\\)?(-| |.)?\\d{1,5})|(\\(?\\d{2,6}\\)?))(-|.| )?(\\d{3,4})(-|.| )?(\\d{4})(( x| ext)\\d{1,5}){0,1}$\"  \/>\r\n\t\r\n\t\r\n<\/div>\n<div id=\"frm_field_12_container\" class=\"frm_form_field form-field  frm_inside_container frm_third\">\r\n\t<label for=\"field_xpb83\" id=\"field_xpb83_label\" class=\"frm_primary_label\">Tipo de pedido\r\n\t\t<span class=\"frm_required\" aria-hidden=\"true\"><\/span>\r\n\t<\/label>\r\n\t\t\t<select name=\"item_meta[12]\" id=\"field_xpb83\"  placeholder=\"Tipo de pedido\" data-invmsg=\"Tipo de pedido is invalid\" aria-invalid=\"false\"  >\n\t\t<option  class=\"frm-select-placeholder\" value=\"\" data-placeholder=\"true\">Tipo de pedido<\/option><option  value=\"Projeto\">Projeto<\/option><option  value=\"Consultoria\">Consultoria<\/option><option  value=\"Engenharia\">Engenharia<\/option><option  value=\"Parceria\">Parceria<\/option><option  value=\"Outro\">Outro<\/option>\t<\/select>\n\t\r\n\t\r\n\t\r\n<\/div>\n<div id=\"frm_field_5_container\" class=\"frm_form_field form-field  frm_inside_container frm_full\">\r\n\t<label for=\"field_9jv0r1\" id=\"field_9jv0r1_label\" class=\"frm_primary_label\">Mensagem\r\n\t\t<span class=\"frm_required\" aria-hidden=\"true\"><\/span>\r\n\t<\/label>\r\n\t<textarea name=\"item_meta[5]\" id=\"field_9jv0r1\" rows=\"4\"  data-invmsg=\"Mensagem is invalid\" aria-invalid=\"false\"  ><\/textarea>\r\n\t\r\n\t\r\n<\/div>\n<div id=\"frm_field_11_container\" class=\"frm_form_field form-field  frm_required_field frm_none_container\">\r\n\t<label for=\"field_hyioq\" id=\"field_hyioq_label\" class=\"frm_primary_label\">Aceita\u00e7\u00e3o\r\n\t\t<span class=\"frm_required\" aria-hidden=\"true\">*<\/span>\r\n\t<\/label>\r\n\t\n<div class=\"frm_checkbox\" role=\"group\" aria-labelledby=\"frm-gdpr-accept-11\">\n\t<label for=\"frm-gdpr-accept-11\">\n\t\t<input type=\"checkbox\" aria-required=\"true\" name=\"item_meta[11]\" id=\"frm-gdpr-accept-11\" value=\"1\" \n\t\t \t\t data-reqmsg=\"Aceita\u00e7\u00e3o cannot be blank.\" aria-required=\"true\" data-invmsg=\"Aceita\u00e7\u00e3o is invalid\" aria-invalid=\"false\"  \t\t\/>\n\t\tConsinto que os dados recolhidos sejam utilizados para analisar e responder ao meu pedido de contacto e para prestar informa\u00e7\u00f5es sobre os servi\u00e7os e solu\u00e7\u00f5es da MYPA\t<\/label>\n<\/div>\n\r\n\t\r\n\t\r\n<\/div>\n<div id=\"frm_field_6_container\" class=\"frm_form_field form-field \">\r\n\t<div class=\"frm_submit frm_flex\">\r\n<button class=\"frm_button_submit\" type=\"submit\"  >ENVIAR PEDIDO<\/button>\r\n\r\n\r\n\r\n<\/div>\r\n<\/div>\n\t<input type=\"hidden\" name=\"item_key\" value=\"\" \/>\n\t\t\t<div id=\"frm_field_24_container\">\n\t\t\t<label for=\"field_igtf\" >\n\t\t\t\tIf you are human, leave this field blank.\t\t\t<\/label>\n\t\t\t<input  id=\"field_igtf\" type=\"text\" class=\"frm_form_field form-field frm_verify\" name=\"item_meta[24]\" value=\"\"  \/>\n\t\t<\/div>\n\t\t<input name=\"frm_state\" type=\"hidden\" value=\"GijeTeQboNKB+1SG0HqTiPcKjfBFwQSNw1aOnLJ7uxs=\" \/><\/div>\n<\/fieldset>\n<\/div>\n\n<\/form>\n<\/div>\n\n\t\t<\/div>\n\t<\/div>\n\n\t\t\t<\/div> \n\t\t<\/div>\n\t<\/div> \n<\/div><\/div>\n\t\t<div id=\"lab\"  data-column-margin=\"none\" data-midnight=\"dark\"  class=\"wpb_row vc_row-fluid vc_row full-width-section has-row-bg-color vc_row-o-equal-height vc_row-flex vc_row-o-content-middle  top_padding_phone_40px bottom_padding_phone_40px\"  style=\"padding-top: 0px; padding-bottom: 0px; --row-bg-color: #F2F0EB;\"><div class=\"row-bg-wrap\" data-bg-animation=\"none\" data-bg-animation-delay=\"\" data-bg-overlay=\"false\"><div class=\"inner-wrap row-bg-layer\" ><div class=\"row-bg viewport-desktop using-bg-color\"  style=\"background-color: #F2F0EB; \"><\/div><\/div><\/div><div class=\"row_col_wrap_12 col span_12 dark left\">\n\t<div  class=\"vc_col-sm-6 wpb_column column_container vc_column_container col has-animation padding-2-percent inherit_tablet inherit_phone \"  data-padding-pos=\"all\" data-has-bg-color=\"false\" data-bg-color=\"\" data-bg-opacity=\"1\" data-animation=\"fade-in-from-left\" data-delay=\"0\" >\n\t\t<div class=\"vc_column-inner\" >\n\t\t\t<div class=\"wpb_wrapper\">\n\t\t\t\t<div class=\"nectar-split-heading  font_line_height_1-2 \" data-align=\"default\" data-m-align=\"inherit\" data-text-effect=\"letter-reveal-bottom\" data-animation-type=\"line-reveal-by-space\" data-animation-delay=\"600\" data-animation-offset=\"\" data-m-rm-animation=\"\" data-stagger=\"\" data-custom-font-size=\"false\" ><h3 style=\"max-width: 480px;\">Contactos diretos<\/h3><\/div><div id=\"fws_6a987f28b5546\" data-midnight=\"\" data-column-margin=\"none\" class=\"wpb_row vc_row-fluid vc_row inner_row vc_row-o-equal-height vc_row-flex bottom_padding_phone_40px\"  style=\"padding-top: 40px; \"><div class=\"row-bg-wrap\"> <div class=\"row-bg\" ><\/div> <\/div><div class=\"row_col_wrap_12_inner col span_12  left\">\n\t<div  class=\"vc_col-sm-6 wpb_column column_container vc_column_container col child_column no-extra-padding inherit_tablet inherit_phone border_right_desktop_1px border_right_tablet_0px border_right_phone_0px border_color_C2C2C2 border_style_solid \"   data-padding-pos=\"all\" data-has-bg-color=\"false\" data-bg-color=\"\" data-bg-opacity=\"1\" data-animation=\"\" data-delay=\"0\" >\n\t\t<div class=\"vc_column-inner\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t\n<div class=\"wpb_text_column wpb_content_element  wpb_animate_when_almost_visible wpb_left-to-right left-to-right delay-600\" >\n\t<h6>ESCRIT\u00d3RIO<\/h6>\n<\/div>\n\n\n\n\n<div class=\"wpb_text_column wpb_content_element  wpb_animate_when_almost_visible wpb_left-to-right left-to-right delay-600\" >\n\t<p>CNO | Centro de Neg\u00f3cios de Oleiros<br \/>\nRua do Monte<br \/>\n4730-325 Vila Verde<\/p>\n<\/div>\n\n\n\n\n\t\t<\/div> \n\t<\/div>\n\t<\/div> \n\n\t<div  class=\"vc_col-sm-6 wpb_column column_container vc_column_container col child_column padding-7-percent top_margin_phone_30px no-extra-padding_tablet no-extra-padding_phone \"   data-padding-pos=\"left\" data-has-bg-color=\"false\" data-bg-color=\"\" data-bg-opacity=\"1\" data-animation=\"\" data-delay=\"0\" >\n\t\t<div class=\"vc_column-inner\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t\n<div class=\"wpb_text_column wpb_content_element  wpb_animate_when_almost_visible wpb_left-to-right left-to-right delay-600\" >\n\t<h6>CONTACTO<\/h6>\n<\/div>\n\n\n\n\n<div class=\"wpb_text_column wpb_content_element  wpb_animate_when_almost_visible wpb_left-to-right left-to-right delay-600\" >\n\t<p>+351 253 929 020<\/p>\n<p><a href=\"mailto:geral@mypa.pt\" target=\"_blank\" rel=\"noopener\" data-fpl-component=\"primitive\">geral@mypa.pt<\/a><\/p>\n<\/div>\n\n\n\n\n\t\t<\/div> \n\t<\/div>\n\t<\/div> \n<\/div><\/div>\n\t\t\t<\/div> \n\t\t<\/div>\n\t<\/div> \n\n\t<div  class=\"vc_col-sm-6 wpb_column column_container vc_column_container col no-extra-padding inherit_tablet inherit_phone \"  data-padding-pos=\"all\" data-has-bg-color=\"false\" data-bg-color=\"\" data-bg-opacity=\"1\" data-animation=\"\" data-delay=\"0\" >\n\t\t<div class=\"vc_column-inner\" >\n\t\t\t<div class=\"wpb_wrapper\">\n\t\t\t\t<div id=\"fws_6a987f28b599b\" data-midnight=\"\" data-column-margin=\"default\" class=\"wpb_row vc_row-fluid vc_row inner_row  min_width_desktop_50vw min_width_tablet_50vw min_width_phone_50vw\"  style=\"\"><div class=\"row-bg-wrap\"> <div class=\"row-bg\" ><\/div> <\/div><div class=\"row_col_wrap_12_inner col span_12  right\">\n\t<div style=\"\" class=\"vc_col-sm-12 wpb_column column_container vc_column_container col child_column no-extra-padding inherit_tablet inherit_phone nectar-mask-reveal-bg nectar-mask-reveal-bg-right-dir nectar-mask-reveal-bg-straight-shape \"  data-using-bg=\"true\" data-bg-cover=\"true\" data-padding-pos=\"all\" data-has-bg-color=\"false\" data-bg-color=\"\" data-bg-opacity=\"1\" data-animation=\"\" data-delay=\"0\" >\n\t\t<div class=\"vc_column-inner\" ><div class=\"column-image-bg-wrap column-bg-layer viewport-desktop\" data-bg-pos=\"center center\" data-bg-animation=\"mask-reveal\" data-bg-overlay=\"false\"><div class=\"inner-wrap\"><div class=\"column-image-bg\" style=\" background-image: url('https:\/\/mypa.gatheomix.com\/wp-content\/uploads\/2026\/07\/Group-871-2.webp'); \"><\/div><\/div><\/div>\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<div class=\"divider-wrap\" data-alignment=\"default\"><div style=\"height: 550px;\" class=\"divider\"><\/div><\/div>\n\t\t<\/div> \n\t<\/div>\n\t<\/div> \n<\/div><\/div>\n\t\t\t<\/div> \n\t\t<\/div>\n\t<\/div> \n<\/div><\/div>\n\t\t<div id=\"lista-icon-stop\"  data-column-margin=\"default\" data-midnight=\"dark\"  class=\"wpb_row vc_row-fluid vc_row full-width-section has-row-bg-color\"  style=\"padding-top: 80px; padding-bottom: 50px; --row-bg-color: #E0E0E0;\"><div class=\"row-bg-wrap\" data-bg-animation=\"none\" data-bg-animation-delay=\"\" data-bg-overlay=\"false\"><div class=\"inner-wrap row-bg-layer\" ><div class=\"row-bg viewport-desktop using-bg-color\"  style=\"background-color: #E0E0E0; \"><\/div><\/div><\/div><div class=\"row_col_wrap_12 col span_12 dark left\">\n\t<div  class=\"vc_col-sm-12 wpb_column column_container vc_column_container col no-extra-padding inherit_tablet inherit_phone \"  data-padding-pos=\"all\" data-has-bg-color=\"false\" data-bg-color=\"\" data-bg-opacity=\"1\" data-animation=\"\" data-delay=\"0\" >\n\t\t<div class=\"vc_column-inner\" >\n\t\t\t<div class=\"wpb_wrapper\">\n\t\t\t\t<div class=\"nectar-split-heading \" data-align=\"left\" data-m-align=\"inherit\" data-text-effect=\"default\" data-animation-type=\"line-reveal-by-space\" data-animation-delay=\"500\" data-animation-offset=\"\" data-m-rm-animation=\"\" data-stagger=\"\" data-custom-font-size=\"false\" ><h3 style=\"max-width: 620px;\">Como podemos ajudar<\/h3><\/div><div class=\"divider-wrap\" data-alignment=\"default\"><div style=\"height: 30px;\" class=\"divider\"><\/div><\/div><div class=\"nectar-fancy-ul\" data-list-icon=\"fa fa-stop\" data-animation=\"true\" data-animation-delay=\"600\" data-color=\"accent-color\" data-spacing=\"25px\" data-alignment=\"left\"> \n<ul>\n<li>\n<h6>Avalia\u00e7\u00e3o t\u00e9cnica de projeto<\/h6>\n<\/li>\n<li>\n<h6>Apoio na defini\u00e7\u00e3o de solu\u00e7\u00f5es construtivas<\/h6>\n<\/li>\n<li>\n<h6>Integra\u00e7\u00e3o de BIM e tecnologias<\/h6>\n<\/li>\n<li>\n<h6>Consultoria estrat\u00e9gica<\/h6>\n<\/li>\n<li>\n<h6>Desenvolvimento de solu\u00e7\u00f5es inovadoras<\/h6>\n<\/li>\n<\/ul>\n <\/div><div class=\"divider-wrap\" data-alignment=\"default\"><div style=\"height: 20px;\" class=\"divider\"><\/div><\/div>\n\t\t\t<\/div> \n\t\t<\/div>\n\t<\/div> \n<\/div><\/div>\n","protected":false},"excerpt":{"rendered":"\u00a0 CONTACTO Vamos transformar o seu projeto? Fale connosco para discutir o seu projeto, explorar solu\u00e7\u00f5es ou avaliar oportunidades de colabora\u00e7\u00e3o. Na MYPA, trabalhamos com arquitetos, construtores, promotores e parceiros...","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-531","page","type-page","status-publish"],"acf":[],"_links":{"self":[{"href":"https:\/\/mypa.gatheomix.com\/en\/wp-json\/wp\/v2\/pages\/531","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/mypa.gatheomix.com\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/mypa.gatheomix.com\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/mypa.gatheomix.com\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/mypa.gatheomix.com\/en\/wp-json\/wp\/v2\/comments?post=531"}],"version-history":[{"count":14,"href":"https:\/\/mypa.gatheomix.com\/en\/wp-json\/wp\/v2\/pages\/531\/revisions"}],"predecessor-version":[{"id":984,"href":"https:\/\/mypa.gatheomix.com\/en\/wp-json\/wp\/v2\/pages\/531\/revisions\/984"}],"wp:attachment":[{"href":"https:\/\/mypa.gatheomix.com\/en\/wp-json\/wp\/v2\/media?parent=531"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}