{"id":300,"date":"2026-07-14T17:21:54","date_gmt":"2026-07-14T17:21:54","guid":{"rendered":"https:\/\/mypa.gatheomix.com\/?page_id=300"},"modified":"2026-08-27T15:31:18","modified_gmt":"2026-08-27T15:31:18","slug":"gestao-de-projeto","status":"publish","type":"page","link":"https:\/\/mypa.gatheomix.com\/en\/gestao-de-projeto\/","title":{"rendered":"Project Management"},"content":{"rendered":"<div id=\"fws_6a987f1adaf04\"  data-column-margin=\"default\" data-midnight=\"light\"  class=\"wpb_row vc_row-fluid vc_row full-width-content vc_row-o-equal-height vc_row-flex vc_row-o-content-middle  zindex-set height_desktop_510px\"  style=\"padding-top: 0px; padding-bottom: 0px;  z-index: 999;\"><div class=\"row-bg-wrap\" data-bg-animation=\"none\" data-bg-animation-delay=\"\" data-bg-overlay=\"false\"><div class=\"inner-wrap row-bg-layer using-image\" ><div class=\"row-bg viewport-desktop using-image\"  style=\"background-image: url(https:\/\/mypa.gatheomix.com\/wp-content\/uploads\/2026\/07\/Group-866-1-1.webp); background-position: center center; background-repeat: no-repeat; \"><\/div><\/div><\/div><div class=\"row_col_wrap_12 col span_12 light center\">\n\t<div  class=\"vc_col-sm-12 wpb_column column_container vc_column_container col no-extra-padding inherit_tablet padding-8-percent_phone\"  data-padding-pos=\"left-right\" data-has-bg-color=\"false\" data-bg-color=\"\" data-bg-opacity=\"1\" data-animation=\"\" data-delay=\"0\" >\n\t\t<div class=\"vc_column-inner\" >\n\t\t\t<div class=\"wpb_wrapper\">\n\t\t\t\t\n<div class=\"wpb_text_column wpb_content_element  wpb_animate_when_almost_visible wpb_fadeInDown fadeInDown vc_custom_1784049733557\"  id=\"icon-stop-porque\">\n\t<p><i class=\"fa fa-stop\"><\/i>\u00a0 PROJECT MANAGEMENT<\/p>\n<\/div>\n\n\n\n<div class=\"nectar-split-heading  font_size_48px font_size_phone_43px\" data-align=\"center\" data-m-align=\"inherit\" data-text-effect=\"letter-reveal-blur-top\" data-animation-type=\"line-reveal-by-space\" data-animation-delay=\"500\" data-animation-offset=\"\" data-m-rm-animation=\"\" data-stagger=\"\" data-custom-font-size=\"true\" style=\"font-size: 48px; line-height: 51.84px;\"><h3 style=\"max-width: 582px;\">Gerimos ambi\u00e7\u00e3o em escala<\/h3><\/div><div class=\"img-with-aniamtion-wrap right custom-width-116px custom-width-phone-85px position_desktop_absolute right_position_desktop_0px bottom_position_desktop_0px z_index_999\" data-max-width=\"custom\" data-max-width-mobile=\"default\" data-shadow=\"none\" data-animation=\"ro-reveal-from-right\" >\n      <div class=\"inner\">\n        <div class=\"hover-wrap\"> \n          <div class=\"hover-wrap-inner\">\n            <img loading=\"lazy\" decoding=\"async\" class=\"img-with-animation skip-lazy\" data-delay=\"600\" height=\"412\" width=\"116\" data-animation=\"ro-reveal-from-right\" src=\"https:\/\/mypa.gatheomix.com\/wp-content\/uploads\/2026\/07\/Vector-10.png\" alt=\"\"  \/>\n          <\/div>\n        <\/div>\n        \n      <\/div>\n    <\/div>\n\t\t\t<\/div> \n\t\t<\/div>\n\t<\/div> \n<\/div><\/div>\n\t\t<div id=\"fws_6a987f1adb32d\"  data-column-margin=\"default\" data-midnight=\"dark\"  class=\"wpb_row vc_row-fluid vc_row full-width-section has-row-bg-color  bottom_padding_phone_100px\"  style=\"padding-top: 25px; padding-bottom: 180px; --row-bg-color: #FAF9F6;\"><div class=\"row-bg-wrap\" data-bg-animation=\"none\" data-bg-animation-delay=\"\" data-bg-overlay=\"false\"><div class=\"inner-wrap row-bg-layer using-image\" ><div class=\"row-bg viewport-desktop using-image using-bg-color\"  style=\"background-image: url(https:\/\/mypa.gatheomix.com\/wp-content\/uploads\/2026\/07\/Group-862-2.png); background-position: center center; background-repeat: no-repeat; background-color: #FAF9F6; \"><\/div><\/div><\/div><div class=\"row_col_wrap_12 col span_12 dark left\">\n\t<div  class=\"vc_col-sm-12 wpb_column column_container vc_column_container col no-extra-padding inherit_tablet inherit_phone flex_gap_desktop_10px\"  data-padding-pos=\"all\" data-has-bg-color=\"false\" data-bg-color=\"\" data-bg-opacity=\"1\" data-animation=\"\" data-delay=\"0\" >\n\t\t<div class=\"vc_column-inner\" >\n\t\t\t<div class=\"wpb_wrapper\">\n\t\t\t\t<div class=\"divider-wrap\" data-alignment=\"default\"><div style=\"margin-top: 12.5px; height: 1px; margin-bottom: 12.5px;\" data-width=\"100%\" data-animate=\"yes\" data-animation-delay=\"600\" data-color=\"default\" class=\"divider-border\"><\/div><\/div><div class=\"img-with-aniamtion-wrap  custom-width-50px\" data-max-width=\"custom\" data-max-width-mobile=\"default\" data-shadow=\"none\" data-animation=\"grow-in\"  style=\"margin-top: 20px; \">\n      <div class=\"inner\">\n        <div class=\"hover-wrap\"> \n          <div class=\"hover-wrap-inner\">\n            <img loading=\"lazy\" decoding=\"async\" class=\"img-with-animation skip-lazy\" data-delay=\"500\" height=\"50\" width=\"50\" data-animation=\"grow-in\" src=\"https:\/\/mypa.gatheomix.com\/wp-content\/uploads\/2026\/07\/Group.png\" alt=\"\"  \/>\n          <\/div>\n        <\/div>\n        \n      <\/div>\n    <\/div><div id=\"fws_6a987f1adb518\" data-midnight=\"\" data-column-margin=\"default\" class=\"wpb_row vc_row-fluid vc_row inner_row\"  style=\"padding-top: 30px; \"><div class=\"row-bg-wrap\"> <div class=\"row-bg\" ><\/div> <\/div><div class=\"row_col_wrap_12_inner col span_12  left\">\n\t<div  class=\"vc_col-sm-3\/5 wpb_column column_container vc_column_container col child_column no-extra-padding force-desktop-text-align-left inherit_tablet inherit_phone flex_layout_desktop_column flex_justify_content_desktop_space-between flex_align_items_desktop_flex-start flex_wrap_desktop_wrap flex_reverse_desktop_false flex_gap_desktop_10px\"   data-padding-pos=\"all\" data-has-bg-color=\"false\" data-bg-color=\"\" data-bg-opacity=\"1\" data-animation=\"\" data-delay=\"0\" >\n\t\t<div class=\"vc_column-inner\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<div class=\"nectar-split-heading  font_size_48px font_size_phone_43px\" data-align=\"left\" data-m-align=\"inherit\" data-text-effect=\"default\" data-animation-type=\"line-reveal-by-space\" data-animation-delay=\"500\" data-animation-offset=\"\" data-m-rm-animation=\"\" data-stagger=\"\" data-custom-font-size=\"true\" style=\"font-size: 48px; line-height: 51.84px;\"><h3 style=\"max-width: 541px;\">Garantimos que a vis\u00e3o se mant\u00e9m at\u00e9 \u00e0 realidade<\/h3><\/div>\n\t\t<\/div> \n\t<\/div>\n\t<\/div> \n\n\t<div style=\"margin-top: 10px; \" class=\"vc_col-sm-2\/5 wpb_column column_container vc_column_container col child_column no-extra-padding force-desktop-text-align-left inherit_tablet inherit_phone\"   data-padding-pos=\"all\" data-has-bg-color=\"false\" data-bg-color=\"\" data-bg-opacity=\"1\" data-animation=\"\" data-delay=\"0\" >\n\t\t<div class=\"vc_column-inner\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t\n<div class=\"wpb_text_column wpb_content_element  wpb_animate_when_almost_visible wpb_fadeInUp fadeInUp vc_custom_1784050217968\" style=\" max-width: 436px; display: inline-block;\">\n\t<p>Na MYPA, a gest\u00e3o de projeto n\u00e3o \u00e9 apenas controlo, \u00a0\u00e9 garantir que cada decis\u00e3o aproxima o projeto da sua vis\u00e3o original.<\/p>\n<\/div>\n\n\n\n\n\t\t<\/div> \n\t<\/div>\n\t<\/div> \n<\/div><\/div>\n\t\t\t<\/div> \n\t\t<\/div>\n\t<\/div> \n<\/div><\/div>\n\t\t<div id=\"icones\"  data-column-margin=\"default\" data-midnight=\"dark\"  class=\"wpb_row vc_row-fluid vc_row full-width-section has-row-bg-color\"  style=\"padding-top: 80px; padding-bottom: 0px; --row-bg-color: #F2F0EB;\"><div class=\"row-bg-wrap\" data-bg-animation=\"none\" data-bg-animation-delay=\"\" data-bg-overlay=\"false\"><div class=\"inner-wrap row-bg-layer\" ><div class=\"row-bg viewport-desktop using-bg-color\"  style=\"background-color: #F2F0EB; \"><\/div><\/div><\/div><div class=\"row_col_wrap_12 col span_12 dark left\">\n\t<div  class=\"vc_col-sm-12 wpb_column column_container vc_column_container col no-extra-padding inherit_tablet inherit_phone flex_gap_desktop_10px\"  data-padding-pos=\"all\" data-has-bg-color=\"false\" data-bg-color=\"\" data-bg-opacity=\"1\" data-animation=\"\" data-delay=\"0\" >\n\t\t<div class=\"vc_column-inner\" >\n\t\t\t<div class=\"wpb_wrapper\">\n\t\t\t\t<div class=\"nectar-split-heading  font_size_48px font_size_phone_43px\" data-align=\"left\" data-m-align=\"inherit\" data-text-effect=\"default\" data-animation-type=\"line-reveal-by-space\" data-animation-delay=\"500\" data-animation-offset=\"\" data-m-rm-animation=\"\" data-stagger=\"\" data-custom-font-size=\"true\" style=\"font-size: 48px; line-height: 51.84px;\"><h3 style=\"max-width: 420px;\">O que fazemos?<\/h3><\/div><div class=\"nectar-flickity not-initialized nectar-carousel\" role=\"region\" aria-roledescription=\"carousel\" aria-label=\"Carousel\" data-centered-cells=\"false\" data-pause-on-hover=\"\" data-touch-icon-color=\"default\" data-control-color=\"default\" data-overflow=\"visible\" data-r-bottom-total=\"\" data-drag-scale=\"true\" data-wrap=\"no-wrap\" data-spacing=\"default\" data-controls=\"next_prev_arrows_overlaid\" data-pagination-alignment=\"default\" data-adaptive-height=\"\" data-border-radius=\"none\" data-column-border=\"true\" data-column-padding=\"30px\" data-format=\"default\" data-autoplay=\"true\" data-autoplay-dur=\"5000\" data-control-style=\"material_pagination\" data-desktop-columns=\"3\" data-small-desktop-columns=\"3\" data-tablet-columns=\"2\" data-phone-columns=\"1\" data-column-color=\"\"><div class=\"flickity-viewport\"> <div class=\"flickity-slider\"><div class=\"cell\"><div class=\"inner-wrap-outer\"><div class=\"inner-wrap\" ><div class=\"img-with-aniamtion-wrap  custom-width-105px\" data-max-width=\"custom\" data-max-width-mobile=\"default\" data-shadow=\"none\" data-animation=\"none\" >\n      <div class=\"inner\">\n        <div class=\"hover-wrap\"> \n          <div class=\"hover-wrap-inner\">\n            <img loading=\"lazy\" decoding=\"async\" class=\"img-with-animation skip-lazy\" data-delay=\"0\" height=\"110\" width=\"110\" data-animation=\"none\" src=\"https:\/\/mypa.gatheomix.com\/wp-content\/uploads\/2026\/07\/Group-810.png\" alt=\"\" srcset=\"https:\/\/mypa.gatheomix.com\/wp-content\/uploads\/2026\/07\/Group-810.png 110w, https:\/\/mypa.gatheomix.com\/wp-content\/uploads\/2026\/07\/Group-810-100x100.png 100w\" sizes=\"auto, (max-width: 110px) 100vw, 110px\" \/>\n          <\/div>\n        <\/div>\n        \n      <\/div>\n    <\/div>\n<div class=\"wpb_text_column wpb_content_element  vc_custom_1784050338847\" style=\" max-width: 221px; display: inline-block;\">\n\t<h6>Planeamento global do projeto<\/h6>\n<\/div>\n\n\n\n<\/div><\/div><\/div><div class=\"cell\"><div class=\"inner-wrap-outer\"><div class=\"inner-wrap\" ><div class=\"img-with-aniamtion-wrap  custom-width-131px\" data-max-width=\"custom\" data-max-width-mobile=\"default\" data-shadow=\"none\" data-animation=\"none\" >\n      <div class=\"inner\">\n        <div class=\"hover-wrap\"> \n          <div class=\"hover-wrap-inner\">\n            <img loading=\"lazy\" decoding=\"async\" class=\"img-with-animation skip-lazy\" data-delay=\"0\" height=\"99\" width=\"131\" data-animation=\"none\" src=\"https:\/\/mypa.gatheomix.com\/wp-content\/uploads\/2026\/07\/Capa_1-4.png\" alt=\"\"  \/>\n          <\/div>\n        <\/div>\n        \n      <\/div>\n    <\/div>\n<div class=\"wpb_text_column wpb_content_element  vc_custom_1784050361990\" style=\" max-width: 269px; display: inline-block;\">\n\t<h6>Coordena\u00e7\u00e3o de equipas e especialidades<\/h6>\n<\/div>\n\n\n\n<\/div><\/div><\/div><div class=\"cell\"><div class=\"inner-wrap-outer\"><div class=\"inner-wrap\" ><div class=\"img-with-aniamtion-wrap  custom-width-105px\" data-max-width=\"custom\" data-max-width-mobile=\"default\" data-shadow=\"none\" data-animation=\"none\"  style=\"margin-top: -8px; \">\n      <div class=\"inner\">\n        <div class=\"hover-wrap\"> \n          <div class=\"hover-wrap-inner\">\n            <img loading=\"lazy\" decoding=\"async\" class=\"img-with-animation skip-lazy\" data-delay=\"0\" height=\"125\" width=\"125\" data-animation=\"none\" src=\"https:\/\/mypa.gatheomix.com\/wp-content\/uploads\/2026\/07\/Group-811.png\" alt=\"\" srcset=\"https:\/\/mypa.gatheomix.com\/wp-content\/uploads\/2026\/07\/Group-811.png 125w, https:\/\/mypa.gatheomix.com\/wp-content\/uploads\/2026\/07\/Group-811-100x100.png 100w\" sizes=\"auto, (max-width: 125px) 100vw, 125px\" \/>\n          <\/div>\n        <\/div>\n        \n      <\/div>\n    <\/div>\n<div class=\"wpb_text_column wpb_content_element  vc_custom_1784050387626\" style=\" max-width: 225px; display: inline-block;\">\n\t<h6>Gest\u00e3o de prazos e custos<\/h6>\n<\/div>\n\n\n\n<\/div><\/div><\/div><div class=\"cell\"><div class=\"inner-wrap-outer\"><div class=\"inner-wrap\" ><div class=\"img-with-aniamtion-wrap  custom-width-85px\" data-max-width=\"custom\" data-max-width-mobile=\"default\" data-shadow=\"none\" data-animation=\"none\"  style=\"margin-bottom: -30px; \">\n      <div class=\"inner\">\n        <div class=\"hover-wrap\"> \n          <div class=\"hover-wrap-inner\">\n            <img loading=\"lazy\" decoding=\"async\" class=\"img-with-animation skip-lazy\" data-delay=\"0\" height=\"132\" width=\"91\" data-animation=\"none\" src=\"https:\/\/mypa.gatheomix.com\/wp-content\/uploads\/2026\/07\/Group-812.png\" alt=\"\"  \/>\n          <\/div>\n        <\/div>\n        \n      <\/div>\n    <\/div>\n<div class=\"wpb_text_column wpb_content_element  vc_custom_1784050408799\" style=\" max-width: 206px; display: inline-block;\">\n\t<h6>Controlo de qualidade<\/h6>\n<\/div>\n\n\n\n<\/div><\/div><\/div><div class=\"cell\"><div class=\"inner-wrap-outer\"><div class=\"inner-wrap\" ><div class=\"img-with-aniamtion-wrap  custom-width-103px\" data-max-width=\"custom\" data-max-width-mobile=\"default\" data-shadow=\"none\" data-animation=\"none\"  style=\"margin-bottom: -14px; \">\n      <div class=\"inner\">\n        <div class=\"hover-wrap\"> \n          <div class=\"hover-wrap-inner\">\n            <img loading=\"lazy\" decoding=\"async\" class=\"img-with-animation skip-lazy\" data-delay=\"0\" height=\"107\" width=\"106\" data-animation=\"none\" src=\"https:\/\/mypa.gatheomix.com\/wp-content\/uploads\/2026\/07\/Capa_1-1-1.png\" alt=\"\" srcset=\"https:\/\/mypa.gatheomix.com\/wp-content\/uploads\/2026\/07\/Capa_1-1-1.png 106w, https:\/\/mypa.gatheomix.com\/wp-content\/uploads\/2026\/07\/Capa_1-1-1-100x100.png 100w\" sizes=\"auto, (max-width: 106px) 100vw, 106px\" \/>\n          <\/div>\n        <\/div>\n        \n      <\/div>\n    <\/div>\n<div class=\"wpb_text_column wpb_content_element  vc_custom_1784050434567\" style=\" max-width: 254px; display: inline-block;\">\n\t<h6>Acompanhamento t\u00e9cnico<\/h6>\n<\/div>\n\n\n\n<\/div><\/div><\/div><\/div><\/div><\/div>\n\t\t\t<\/div> \n\t\t<\/div>\n\t<\/div> \n<\/div><\/div>\n\t\t<div id=\"lab\"  data-column-margin=\"default\" data-midnight=\"light\"  class=\"wpb_row vc_row-fluid vc_row full-width-section has-row-bg-color vc_row-o-equal-height vc_row-flex vc_row-o-content-middle  top_padding_phone_30px bottom_padding_phone_30px\"  style=\"padding-top: 0px; padding-bottom: 0px; --row-bg-color: #1C1C1C;\"><div class=\"row-bg-wrap\" data-bg-animation=\"none\" data-bg-animation-delay=\"\" data-bg-overlay=\"false\"><div class=\"inner-wrap row-bg-layer\" ><div class=\"row-bg viewport-desktop using-bg-color\"  style=\"background-color: #1C1C1C; \"><\/div><\/div><\/div><div class=\"row_col_wrap_12 col span_12 light left\">\n\t<div  class=\"vc_col-sm-3\/5 wpb_column column_container vc_column_container col padding-4-percent inherit_tablet inherit_phone\"  data-padding-pos=\"all\" data-has-bg-color=\"false\" data-bg-color=\"\" data-bg-opacity=\"1\" data-animation=\"\" data-delay=\"0\" >\n\t\t<div class=\"vc_column-inner\" >\n\t\t\t<div class=\"wpb_wrapper\">\n\t\t\t\t<div class=\"nectar-split-heading  font_size_36px font_line_height_1-2\" data-align=\"default\" data-m-align=\"inherit\" data-text-effect=\"default\" data-animation-type=\"line-reveal-by-space\" data-animation-delay=\"0\" data-animation-offset=\"\" data-m-rm-animation=\"\" data-stagger=\"\" data-custom-font-size=\"true\" style=\"font-size: 36px; line-height: 38.88px;\"><h3 >Abordagem<\/h3><\/div><div class=\"nectar-fancy-ul link_style_underline nectar-link-underline-effect\" data-list-icon=\"icon-salient-check\" data-animation=\"true\" data-animation-delay=\"600\" data-color=\"extra-color-2\" data-spacing=\"25px\" data-alignment=\"left\"> \n<ul>\n<li>Gest\u00e3o colaborativa<\/li>\n<li>Comunica\u00e7\u00e3o cont\u00ednua<\/li>\n<li>Monitoriza\u00e7\u00e3o permanente<\/li>\n<li>Decis\u00e3o baseada em dados<\/li>\n<\/ul>\n <\/div>\n\t\t\t<\/div> \n\t\t<\/div>\n\t<\/div> \n\n\t<div  class=\"vc_col-sm-2\/5 wpb_column column_container vc_column_container col no-extra-padding inherit_tablet inherit_phone\"  data-padding-pos=\"all\" data-has-bg-color=\"false\" data-bg-color=\"\" data-bg-opacity=\"1\" data-animation=\"\" data-delay=\"0\" >\n\t\t<div class=\"vc_column-inner\" >\n\t\t\t<div class=\"wpb_wrapper\">\n\t\t\t\t<div id=\"fws_6a987f1adc252\" data-midnight=\"\" data-column-margin=\"default\" class=\"wpb_row vc_row-fluid vc_row inner_row  min_width_desktop_44vw min_width_tablet_50vw min_width_phone_50vw\"  style=\"\"><div class=\"row-bg-wrap\"> <div class=\"row-bg\" ><\/div> <\/div><div class=\"row_col_wrap_12_inner col span_12  right\">\n\t<div style=\"\" class=\"vc_col-sm-12 wpb_column column_container vc_column_container col child_column no-extra-padding inherit_tablet inherit_phone nectar-mask-reveal-bg nectar-mask-reveal-bg-left-dir nectar-mask-reveal-bg-straight-shape\"  data-using-bg=\"true\" data-bg-cover=\"true\" data-padding-pos=\"all\" data-has-bg-color=\"false\" data-bg-color=\"\" data-bg-opacity=\"1\" data-animation=\"\" data-delay=\"0\" >\n\t\t<div class=\"vc_column-inner\" ><div class=\"column-image-bg-wrap column-bg-layer viewport-desktop\" data-n-parallax-bg=\"true\" data-parallax-speed=\"minimum\" data-bg-pos=\"center center\" data-bg-animation=\"mask-reveal\" data-bg-overlay=\"false\"><div class=\"inner-wrap\"><div class=\"column-image-bg parallax-layer\" style=\" background-image: url('https:\/\/mypa.gatheomix.com\/wp-content\/uploads\/2026\/07\/Atividade_Gestao-de-Projeto_img2.webp'); \"><\/div><\/div><\/div>\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<div class=\"divider-wrap height_phone_500px\" data-alignment=\"default\"><div style=\"height: 600px;\" class=\"divider\"><\/div><\/div>\n\t\t<\/div> \n\t<\/div>\n\t<\/div> \n<\/div><\/div>\n\t\t\t<\/div> \n\t\t<\/div>\n\t<\/div> \n<\/div><\/div>\n\t\t<div id=\"fws_6a987f1adc403\"  data-column-margin=\"default\" data-midnight=\"dark\"  class=\"wpb_row vc_row-fluid vc_row full-width-section\"  style=\"padding-top: 80px; padding-bottom: 80px; \"><div class=\"row-bg-wrap\" data-bg-animation=\"none\" data-bg-animation-delay=\"\" data-bg-overlay=\"false\"><div class=\"inner-wrap row-bg-layer\" ><div class=\"row-bg viewport-desktop\"  style=\"\"><\/div><\/div><\/div><div class=\"row_col_wrap_12 col span_12 dark left\">\n\t<div  class=\"vc_col-sm-12 wpb_column column_container vc_column_container col no-extra-padding inherit_tablet inherit_phone flex_gap_desktop_10px\"  data-padding-pos=\"all\" data-has-bg-color=\"false\" data-bg-color=\"\" data-bg-opacity=\"1\" data-animation=\"\" data-delay=\"0\" >\n\t\t<div class=\"vc_column-inner\" >\n\t\t\t<div class=\"wpb_wrapper\">\n\t\t\t\t<div class=\"nectar-split-heading\" data-align=\"left\" data-m-align=\"inherit\" data-text-effect=\"default\" data-animation-type=\"line-reveal-by-space\" data-animation-delay=\"500\" data-animation-offset=\"\" data-m-rm-animation=\"\" data-stagger=\"\" data-custom-font-size=\"false\" ><h3 style=\"max-width: 440px;\">How we work<\/h3><\/div>\n\t\t\t<\/div> \n\t\t<\/div>\n\t<\/div> \n<\/div><\/div>\n\t\t<div id=\"fws_6a987f1adc4da\"  data-column-margin=\"none\" data-midnight=\"dark\"  class=\"wpb_row vc_row-fluid vc_row full-width-section vc_row-o-equal-height vc_row-flex\"  style=\"padding-top: 0px; padding-bottom: 90px; \"><div class=\"row-bg-wrap\" data-bg-animation=\"none\" data-bg-animation-delay=\"\" data-bg-overlay=\"false\"><div class=\"inner-wrap row-bg-layer\" ><div class=\"row-bg viewport-desktop\"  style=\"\"><\/div><\/div><\/div><div class=\"row_col_wrap_12 col span_12 dark left\">\n\t<div  class=\"vc_col-sm-3 wpb_column column_container vc_column_container col has-animation no-extra-padding inherit_tablet inherit_phone flex_layout_desktop_column flex_justify_content_desktop_space-between flex_align_items_desktop_flex-start flex_wrap_desktop_nowrap flex_reverse_desktop_false flex_gap_desktop_10px\"  data-padding-pos=\"all\" data-has-bg-color=\"false\" data-bg-color=\"\" data-bg-opacity=\"1\" data-animation=\"reveal-from-left\" data-delay=\"0\" >\n\t\t<div class=\"vc_column-inner\" >\n\t\t\t<div class=\"wpb_wrapper\">\n\t\t\t\t<div class=\"nectar-split-heading  font_size_36px\" data-align=\"default\" data-m-align=\"inherit\" data-text-effect=\"letter-reveal-bottom\" data-animation-type=\"line-reveal-by-space\" data-animation-delay=\"300\" data-animation-offset=\"\" data-m-rm-animation=\"\" data-stagger=\"\" data-custom-font-size=\"true\" style=\"font-size: 36px; line-height: 38.88px;\"><h5 style=\" color: #4273B8;\">01<\/h5><\/div><div class=\"divider-wrap\" data-alignment=\"default\"><div style=\"margin-top: 12.5px; width: 36px; height: 2px; margin-bottom: 12.5px;\" data-width=\"36px\" data-animate=\"yes\" data-animation-delay=\"\" data-color=\"extra-color-2\" class=\"divider-small-border\"><\/div><\/div>\n<div class=\"wpb_text_column wpb_content_element  vc_custom_1784051245684\" style=\" max-width: 281px; display: inline-block;\">\n\t<h6>Planeamento\u2028estrat\u00e9gico<\/h6>\n<\/div>\n\n\n\n<div class=\"divider-wrap\" data-alignment=\"default\"><div style=\"height: 40px;\" class=\"divider\"><\/div><\/div><div class=\"img-with-aniamtion-wrap  position_desktop_absolute bottom_position_desktop_0px\" data-max-width=\"100%\" data-max-width-mobile=\"default\" data-shadow=\"none\" data-animation=\"none\"  style=\"margin-top: 30px; \">\n      <div class=\"inner\">\n        <div class=\"hover-wrap\"> \n          <div class=\"hover-wrap-inner\">\n            <img loading=\"lazy\" decoding=\"async\" class=\"img-with-animation skip-lazy\" data-delay=\"0\" height=\"12\" width=\"510\" data-animation=\"none\" src=\"https:\/\/mypa.gatheomix.com\/wp-content\/uploads\/2026\/07\/Group-866-3.png\" alt=\"\" srcset=\"https:\/\/mypa.gatheomix.com\/wp-content\/uploads\/2026\/07\/Group-866-3.png 510w, https:\/\/mypa.gatheomix.com\/wp-content\/uploads\/2026\/07\/Group-866-3-300x7.png 300w, https:\/\/mypa.gatheomix.com\/wp-content\/uploads\/2026\/07\/Group-866-3-500x12.png 500w\" sizes=\"auto, (max-width: 510px) 100vw, 510px\" \/>\n          <\/div>\n        <\/div>\n        \n      <\/div>\n    <\/div>\n\t\t\t<\/div> \n\t\t<\/div>\n\t<\/div> \n\n\t<div  class=\"vc_col-sm-3 wpb_column column_container vc_column_container col has-animation no-extra-padding top_margin_phone_20px inherit_tablet inherit_phone flex_layout_desktop_column flex_justify_content_desktop_flex-start flex_align_items_desktop_flex-start flex_wrap_desktop_nowrap flex_reverse_desktop_false flex_gap_desktop_10px\"  data-padding-pos=\"all\" data-has-bg-color=\"false\" data-bg-color=\"\" data-bg-opacity=\"1\" data-animation=\"reveal-from-left\" data-delay=\"400\" >\n\t\t<div class=\"vc_column-inner\" >\n\t\t\t<div class=\"wpb_wrapper\">\n\t\t\t\t<div class=\"nectar-split-heading  font_size_36px\" data-align=\"default\" data-m-align=\"inherit\" data-text-effect=\"letter-reveal-bottom\" data-animation-type=\"line-reveal-by-space\" data-animation-delay=\"700\" data-animation-offset=\"\" data-m-rm-animation=\"\" data-stagger=\"\" data-custom-font-size=\"true\" style=\"font-size: 36px; line-height: 38.88px;\"><h5 style=\" color: #4273B8;\">02<\/h5><\/div><div class=\"divider-wrap\" data-alignment=\"default\"><div style=\"margin-top: 12.5px; width: 36px; height: 2px; margin-bottom: 12.5px;\" data-width=\"36px\" data-animate=\"yes\" data-animation-delay=\"\" data-color=\"extra-color-2\" class=\"divider-small-border\"><\/div><\/div>\n<div class=\"wpb_text_column wpb_content_element  vc_custom_1784051388238\" style=\" max-width: 170px; display: inline-block;\">\n\t<h6>Coordena\u00e7\u00e3o\u2028de equipas<\/h6>\n<\/div>\n\n\n\n<div class=\"divider-wrap\" data-alignment=\"default\"><div style=\"height: 40px;\" class=\"divider\"><\/div><\/div><div class=\"img-with-aniamtion-wrap  position_desktop_absolute bottom_position_desktop_0px\" data-max-width=\"100%\" data-max-width-mobile=\"default\" data-shadow=\"none\" data-animation=\"none\"  style=\"margin-top: 30px; \">\n      <div class=\"inner\">\n        <div class=\"hover-wrap\"> \n          <div class=\"hover-wrap-inner\">\n            <img loading=\"lazy\" decoding=\"async\" class=\"img-with-animation skip-lazy\" data-delay=\"0\" height=\"12\" width=\"510\" data-animation=\"none\" src=\"https:\/\/mypa.gatheomix.com\/wp-content\/uploads\/2026\/07\/Group-866-3.png\" alt=\"\" srcset=\"https:\/\/mypa.gatheomix.com\/wp-content\/uploads\/2026\/07\/Group-866-3.png 510w, https:\/\/mypa.gatheomix.com\/wp-content\/uploads\/2026\/07\/Group-866-3-300x7.png 300w, https:\/\/mypa.gatheomix.com\/wp-content\/uploads\/2026\/07\/Group-866-3-500x12.png 500w\" sizes=\"auto, (max-width: 510px) 100vw, 510px\" \/>\n          <\/div>\n        <\/div>\n        \n      <\/div>\n    <\/div>\n\t\t\t<\/div> \n\t\t<\/div>\n\t<\/div> \n\n\t<div  class=\"vc_col-sm-3 wpb_column column_container vc_column_container col has-animation no-extra-padding top_margin_phone_20px inherit_tablet inherit_phone flex_layout_desktop_column flex_justify_content_desktop_flex-start flex_align_items_desktop_flex-start flex_wrap_desktop_nowrap flex_reverse_desktop_false flex_gap_desktop_10px\"  data-padding-pos=\"all\" data-has-bg-color=\"false\" data-bg-color=\"\" data-bg-opacity=\"1\" data-animation=\"reveal-from-left\" data-delay=\"800\" >\n\t\t<div class=\"vc_column-inner\" >\n\t\t\t<div class=\"wpb_wrapper\">\n\t\t\t\t<div class=\"nectar-split-heading  font_size_36px\" data-align=\"default\" data-m-align=\"inherit\" data-text-effect=\"letter-reveal-bottom\" data-animation-type=\"line-reveal-by-space\" data-animation-delay=\"1100\" data-animation-offset=\"\" data-m-rm-animation=\"\" data-stagger=\"\" data-custom-font-size=\"true\" style=\"font-size: 36px; line-height: 38.88px;\"><h5 style=\" color: #4273B8;\">03<\/h5><\/div><div class=\"divider-wrap\" data-alignment=\"default\"><div style=\"margin-top: 12.5px; width: 36px; height: 2px; margin-bottom: 12.5px;\" data-width=\"36px\" data-animate=\"yes\" data-animation-delay=\"\" data-color=\"extra-color-2\" class=\"divider-small-border\"><\/div><\/div>\n<div class=\"wpb_text_column wpb_content_element  vc_custom_1784051420901\" style=\" max-width: 160px; display: inline-block;\">\n\t<h6>Integra\u00e7\u00e3o\u2028de processos<\/h6>\n<\/div>\n\n\n\n<div class=\"divider-wrap\" data-alignment=\"default\"><div style=\"height: 40px;\" class=\"divider\"><\/div><\/div><div class=\"img-with-aniamtion-wrap  position_desktop_absolute bottom_position_desktop_0px\" data-max-width=\"100%\" data-max-width-mobile=\"default\" data-shadow=\"none\" data-animation=\"none\"  style=\"margin-top: 30px; \">\n      <div class=\"inner\">\n        <div class=\"hover-wrap\"> \n          <div class=\"hover-wrap-inner\">\n            <img loading=\"lazy\" decoding=\"async\" class=\"img-with-animation skip-lazy\" data-delay=\"0\" height=\"12\" width=\"510\" data-animation=\"none\" src=\"https:\/\/mypa.gatheomix.com\/wp-content\/uploads\/2026\/07\/Group-866-3.png\" alt=\"\" srcset=\"https:\/\/mypa.gatheomix.com\/wp-content\/uploads\/2026\/07\/Group-866-3.png 510w, https:\/\/mypa.gatheomix.com\/wp-content\/uploads\/2026\/07\/Group-866-3-300x7.png 300w, https:\/\/mypa.gatheomix.com\/wp-content\/uploads\/2026\/07\/Group-866-3-500x12.png 500w\" sizes=\"auto, (max-width: 510px) 100vw, 510px\" \/>\n          <\/div>\n        <\/div>\n        \n      <\/div>\n    <\/div>\n\t\t\t<\/div> \n\t\t<\/div>\n\t<\/div> \n\n\t<div  class=\"vc_col-sm-3 wpb_column column_container vc_column_container col has-animation no-extra-padding top_margin_phone_20px inherit_tablet inherit_phone flex_layout_desktop_column flex_justify_content_desktop_flex-start flex_align_items_desktop_flex-start flex_wrap_desktop_nowrap flex_reverse_desktop_false flex_gap_desktop_10px\"  data-padding-pos=\"all\" data-has-bg-color=\"false\" data-bg-color=\"\" data-bg-opacity=\"1\" data-animation=\"reveal-from-left\" data-delay=\"1200\" >\n\t\t<div class=\"vc_column-inner\" >\n\t\t\t<div class=\"wpb_wrapper\">\n\t\t\t\t<div class=\"nectar-split-heading  font_size_36px\" data-align=\"default\" data-m-align=\"inherit\" data-text-effect=\"letter-reveal-bottom\" data-animation-type=\"line-reveal-by-space\" data-animation-delay=\"1500\" data-animation-offset=\"\" data-m-rm-animation=\"\" data-stagger=\"\" data-custom-font-size=\"true\" style=\"font-size: 36px; line-height: 38.88px;\"><h5 style=\" color: #4273B8;\">04<\/h5><\/div><div class=\"divider-wrap\" data-alignment=\"default\"><div style=\"margin-top: 12.5px; width: 36px; height: 2px; margin-bottom: 12.5px;\" data-width=\"36px\" data-animate=\"yes\" data-animation-delay=\"\" data-color=\"extra-color-2\" class=\"divider-small-border\"><\/div><\/div>\n<div class=\"wpb_text_column wpb_content_element  vc_custom_1784051308617\" style=\" max-width: 190px; display: inline-block;\">\n\t<h6>Execu\u00e7\u00e3o\u2028eficiente<\/h6>\n<\/div>\n\n\n\n<div class=\"divider-wrap\" data-alignment=\"default\"><div style=\"height: 40px;\" class=\"divider\"><\/div><\/div><div class=\"img-with-aniamtion-wrap  position_desktop_absolute bottom_position_desktop_0px\" data-max-width=\"100%\" data-max-width-mobile=\"default\" data-shadow=\"none\" data-animation=\"none\"  style=\"margin-top: 30px; \">\n      <div class=\"inner\">\n        <div class=\"hover-wrap\"> \n          <div class=\"hover-wrap-inner\">\n            <img loading=\"lazy\" decoding=\"async\" class=\"img-with-animation skip-lazy\" data-delay=\"0\" height=\"12\" width=\"510\" data-animation=\"none\" src=\"https:\/\/mypa.gatheomix.com\/wp-content\/uploads\/2026\/07\/Group-866-5.png\" alt=\"\" srcset=\"https:\/\/mypa.gatheomix.com\/wp-content\/uploads\/2026\/07\/Group-866-5.png 510w, https:\/\/mypa.gatheomix.com\/wp-content\/uploads\/2026\/07\/Group-866-5-300x7.png 300w, https:\/\/mypa.gatheomix.com\/wp-content\/uploads\/2026\/07\/Group-866-5-500x12.png 500w\" sizes=\"auto, (max-width: 510px) 100vw, 510px\" \/>\n          <\/div>\n        <\/div>\n        \n      <\/div>\n    <\/div>\n\t\t\t<\/div> \n\t\t<\/div>\n\t<\/div> \n<\/div><\/div>\n\t\t<div id=\"lista-icon-stop\"  data-column-margin=\"default\" data-midnight=\"dark\"  class=\"wpb_row vc_row-fluid vc_row full-width-section has-row-bg-color\"  style=\"padding-top: 70px; padding-bottom: 50px; --row-bg-color: #E0E0E0;\"><div class=\"row-bg-wrap\" data-bg-animation=\"none\" data-bg-animation-delay=\"\" data-bg-overlay=\"false\"><div class=\"inner-wrap row-bg-layer\" ><div class=\"row-bg viewport-desktop using-bg-color\"  style=\"background-color: #E0E0E0; \"><\/div><\/div><\/div><div class=\"row_col_wrap_12 col span_12 dark left\">\n\t<div  class=\"vc_col-sm-6 wpb_column column_container vc_column_container col no-extra-padding inherit_tablet inherit_phone flex_layout_desktop_column flex_justify_content_desktop_space-between flex_align_items_desktop_flex-start flex_wrap_desktop_nowrap flex_reverse_desktop_false\"  data-padding-pos=\"all\" data-has-bg-color=\"false\" data-bg-color=\"\" data-bg-opacity=\"1\" data-animation=\"\" data-delay=\"0\" >\n\t\t<div class=\"vc_column-inner\" >\n\t\t\t<div class=\"wpb_wrapper\">\n\t\t\t\t<div class=\"nectar-split-heading\" data-align=\"left\" data-m-align=\"inherit\" data-text-effect=\"default\" data-animation-type=\"line-reveal-by-space\" data-animation-delay=\"500\" data-animation-offset=\"\" data-m-rm-animation=\"\" data-stagger=\"\" data-custom-font-size=\"false\" ><h3 style=\"max-width: 328px;\">Valor para o projeto<\/h3><\/div><div class=\"divider-wrap\" data-alignment=\"default\"><div style=\"height: 70px;\" class=\"divider\"><\/div><\/div><div class=\"nectar-fancy-ul\" data-list-icon=\"fa fa-stop\" data-animation=\"true\" data-animation-delay=\"600\" data-color=\"accent-color\" data-spacing=\"25px\" data-alignment=\"left\"> \n<ul>\n<li>\n<h6>Previsibilidade<\/h6>\n<\/li>\n<li>\n<h6>Risk reduction<\/h6>\n<\/li>\n<li>\n<h6>Controlo de or\u00e7amento<\/h6>\n<\/li>\n<li>\n<h6>Cumprimento de prazos<\/h6>\n<\/li>\n<\/ul>\n <\/div><div class=\"divider-wrap\" data-alignment=\"default\"><div style=\"height: 20px;\" class=\"divider\"><\/div><\/div>\n\t\t\t<\/div> \n\t\t<\/div>\n\t<\/div> \n\n\t<div  class=\"vc_col-sm-6 wpb_column column_container vc_column_container col has-animation padding-4-percent inherit_tablet inherit_phone\"  data-padding-pos=\"top\" data-has-bg-color=\"false\" data-bg-color=\"\" data-bg-opacity=\"1\" data-animation=\"reveal-from-bottom\" data-delay=\"0\" data-animation-offset=\"60%\" >\n\t\t<div class=\"vc_column-inner\" >\n\t\t\t<div class=\"wpb_wrapper\">\n\t\t\t\t<div class=\"img-with-aniamtion-wrap\" data-max-width=\"100%\" data-max-width-mobile=\"default\" data-shadow=\"none\" data-animation=\"none\" >\n      <div class=\"inner\">\n        <div class=\"hover-wrap\"> \n          <div class=\"hover-wrap-inner\">\n            <img loading=\"lazy\" decoding=\"async\" class=\"img-with-animation skip-lazy\" data-delay=\"0\" height=\"794\" width=\"779\" data-animation=\"none\" src=\"https:\/\/mypa.gatheomix.com\/wp-content\/uploads\/2026\/07\/Atividade_Investigacao-e-Desenvolvimento_im3.webp\" alt=\"\" srcset=\"https:\/\/mypa.gatheomix.com\/wp-content\/uploads\/2026\/07\/Atividade_Investigacao-e-Desenvolvimento_im3.webp 779w, https:\/\/mypa.gatheomix.com\/wp-content\/uploads\/2026\/07\/Atividade_Investigacao-e-Desenvolvimento_im3-294x300.webp 294w, https:\/\/mypa.gatheomix.com\/wp-content\/uploads\/2026\/07\/Atividade_Investigacao-e-Desenvolvimento_im3-768x783.webp 768w\" sizes=\"auto, (max-width: 779px) 100vw, 779px\" \/>\n          <\/div>\n        <\/div>\n        \n      <\/div>\n    <\/div>\n\t\t\t<\/div> \n\t\t<\/div>\n\t<\/div> \n<\/div><\/div>\n\t\t<div id=\"fws_6a987f1add120\"  data-column-margin=\"default\" data-midnight=\"light\"  class=\"wpb_row vc_row-fluid vc_row full-width-section vc_row-o-equal-height vc_row-flex vc_row-o-content-middle  height_desktop_300px top_padding_phone_40px bottom_padding_phone_40px\"  style=\"padding-top: 30px; padding-bottom: 0px; \"><div class=\"row-bg-wrap\" data-bg-animation=\"none\" data-bg-animation-delay=\"\" data-bg-overlay=\"false\"><div class=\"inner-wrap row-bg-layer using-image\" ><div class=\"row-bg viewport-desktop using-image\"  style=\"background-image: url(https:\/\/mypa.gatheomix.com\/wp-content\/uploads\/2026\/07\/Group-866-3.webp); background-position: center center; background-repeat: no-repeat; \"><\/div><\/div><\/div><div class=\"row_col_wrap_12 col span_12 light left\">\n\t<div  class=\"vc_col-sm-12 wpb_column column_container vc_column_container col no-extra-padding inherit_tablet inherit_phone flex_gap_desktop_10px\"  data-padding-pos=\"all\" data-has-bg-color=\"false\" data-bg-color=\"\" data-bg-opacity=\"1\" data-animation=\"\" data-delay=\"0\" >\n\t\t<div class=\"vc_column-inner\" >\n\t\t\t<div class=\"wpb_wrapper\">\n\t\t\t\t<div class=\"nectar-split-heading  font_size_48px\" data-align=\"default\" data-m-align=\"inherit\" data-text-effect=\"letter-reveal-blur-bottom\" data-animation-type=\"line-reveal-by-space\" data-animation-delay=\"0\" data-animation-offset=\"\" data-m-rm-animation=\"\" data-stagger=\"\" data-custom-font-size=\"true\" style=\"font-size: 48px; line-height: 51.84px;\"><h5 style=\"max-width: 858px;\">Gerimos projetos com a mesma ambi\u00e7\u00e3o com que s\u00e3o concebidos.<\/h5><\/div><div class=\"img-with-aniamtion-wrap right custom-width-160px position_desktop_absolute right_position_desktop_0px translate_y_desktop_-35px translate_y_phone_15px z_index_999\" data-max-width=\"custom\" data-max-width-mobile=\"default\" data-shadow=\"none\" data-animation=\"none\" >\n      <div class=\"inner\">\n        <div class=\"hover-wrap\"> \n          <div class=\"hover-wrap-inner\">\n            <img loading=\"lazy\" decoding=\"async\" class=\"img-with-animation skip-lazy\" data-delay=\"0\" height=\"160\" width=\"160\" data-animation=\"none\" src=\"https:\/\/mypa.gatheomix.com\/wp-content\/uploads\/2026\/07\/Vector-11.png\" alt=\"\" srcset=\"https:\/\/mypa.gatheomix.com\/wp-content\/uploads\/2026\/07\/Vector-11.png 160w, https:\/\/mypa.gatheomix.com\/wp-content\/uploads\/2026\/07\/Vector-11-150x150.png 150w, https:\/\/mypa.gatheomix.com\/wp-content\/uploads\/2026\/07\/Vector-11-140x140.png 140w, https:\/\/mypa.gatheomix.com\/wp-content\/uploads\/2026\/07\/Vector-11-100x100.png 100w\" sizes=\"auto, (max-width: 160px) 100vw, 160px\" \/>\n          <\/div>\n        <\/div>\n        \n      <\/div>\n    <\/div>\n\t\t\t<\/div> \n\t\t<\/div>\n\t<\/div> \n<\/div><\/div>\n\t\t<div id=\"fws_6a987f1add35a\"  data-column-margin=\"default\" data-midnight=\"light\"  class=\"wpb_row vc_row-fluid vc_row full-width-section has-row-bg-color vc_row-o-equal-height vc_row-flex vc_row-o-content-middle  height_desktop_430px top_padding_phone_45px bottom_padding_phone_30px\"  style=\"padding-top: 0px; padding-bottom: 0px; --row-bg-color: #1C1C1C;\"><div class=\"row-bg-wrap\" data-bg-animation=\"none\" data-bg-animation-delay=\"\" data-bg-overlay=\"false\"><div class=\"inner-wrap row-bg-layer\" ><div class=\"row-bg viewport-desktop using-bg-color\"  style=\"background-color: #1C1C1C; \"><\/div><\/div><\/div><div class=\"row_col_wrap_12 col span_12 light left\">\n\t<div  class=\"vc_col-sm-12 wpb_column column_container vc_column_container col no-extra-padding inherit_tablet inherit_phone flex_gap_desktop_10px\"  data-padding-pos=\"all\" data-has-bg-color=\"false\" data-bg-color=\"\" data-bg-opacity=\"1\" data-animation=\"\" data-delay=\"0\" >\n\t\t<div class=\"vc_column-inner\" >\n\t\t\t<div class=\"wpb_wrapper\">\n\t\t\t\t<div class=\"nectar-split-heading  font_size_48px\" data-align=\"default\" data-m-align=\"inherit\" data-text-effect=\"letter-reveal-blur-bottom\" data-animation-type=\"line-reveal-by-space\" data-animation-delay=\"0\" data-animation-offset=\"\" data-m-rm-animation=\"\" data-stagger=\"\" data-custom-font-size=\"true\" style=\"font-size: 48px; line-height: 51.84px;\"><h3 style=\" color: #FAC424;\">Request a quote<\/h3><\/div><div id=\"fws_6a987f1add443\" data-midnight=\"\" data-column-margin=\"default\" class=\"wpb_row vc_row-fluid vc_row inner_row vc_row-o-equal-height vc_row-flex vc_row-o-content-bottom\"  style=\"padding-top: 30px; padding-bottom: 60px; \"><div class=\"row-bg-wrap\"> <div class=\"row-bg\" ><\/div> <\/div><div class=\"row_col_wrap_12_inner col span_12  left\">\n\t<div  class=\"vc_col-sm-8 wpb_column column_container vc_column_container col child_column has-animation no-extra-padding inherit_tablet inherit_phone\"   data-padding-pos=\"right\" data-has-bg-color=\"false\" data-bg-color=\"\" data-bg-opacity=\"1\" data-animation=\"slight-fade-in-from-bottom\" data-delay=\"600\" >\n\t\t<div class=\"vc_column-inner\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<div class=\"nectar-responsive-text font_size_desktop_20px font_line_height_1-3 nectar-link-underline-effect\" style=\"max-width: 680px;\" data-inherit-heading-family=\"h2\"><p>Are you planning to build using a light steel frame?<\/p>\n<p>Our team is on hand to review your project and propose the most suitable solution.<\/p>\n<\/div>\n\t\t<\/div> \n\t<\/div>\n\t<\/div> \n\n\t<div  class=\"vc_col-sm-4 wpb_column column_container vc_column_container col child_column has-animation no-extra-padding top_margin_phone_15px inherit_tablet inherit_phone\"   data-padding-pos=\"all\" data-has-bg-color=\"false\" data-bg-color=\"\" data-bg-opacity=\"1\" data-animation=\"zoom-out\" data-delay=\"800\" >\n\t\t<div class=\"vc_column-inner\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<div class=\"nectar-cta  hover_color_FAC424 text_hover_color_000000 border_color_ffffff hover_border_color_FAC424 border_thickness_1px border_radius_0px alignment_tablet_default alignment_phone_default display_tablet_inherit display_phone_inherit translate_x_desktop_26px\" data-color=\"default\" data-using-bg=\"false\" data-style=\"basic\" data-display=\"block\" data-alignment=\"center\" data-text-color=\"custom\" style=\"--nectar-text-color: #FFFFFF; --nectar-button-color: var(--nectar-default); --nectar-button-color-hover: #FAC424; --nectar-text-color-hover: #000000; --nectar-icon-gap: 10px; \"><span style=\"color: #FFFFFF;\" class=\"nectar-button-type\"><span class=\"link_wrap\" style=\"padding-top: 9px; padding-right: 16px; padding-bottom: 9px; padding-left: 16px;\"><a  class=\"link_text\" role=\"button\" href=\"#\"><span class=\"text\">Request a Quote<\/span><\/a><\/span><\/span><\/div>\n\t\t<\/div> \n\t<\/div>\n\t<\/div> \n<\/div><\/div>\n\t\t\t<\/div> \n\t\t<\/div>\n\t<\/div> \n<\/div><\/div>","protected":false},"excerpt":{"rendered":"\u00a0 GEST\u00c3O DE PROJETO Gerimos ambi\u00e7\u00e3o em escala Garantimos que a vis\u00e3o se mant\u00e9m at\u00e9 \u00e0 realidade Na MYPA, a gest\u00e3o de projeto n\u00e3o \u00e9 apenas controlo, \u00a0\u00e9 garantir que...","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-300","page","type-page","status-publish"],"acf":[],"_links":{"self":[{"href":"https:\/\/mypa.gatheomix.com\/en\/wp-json\/wp\/v2\/pages\/300","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/mypa.gatheomix.com\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/mypa.gatheomix.com\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/mypa.gatheomix.com\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/mypa.gatheomix.com\/en\/wp-json\/wp\/v2\/comments?post=300"}],"version-history":[{"count":11,"href":"https:\/\/mypa.gatheomix.com\/en\/wp-json\/wp\/v2\/pages\/300\/revisions"}],"predecessor-version":[{"id":983,"href":"https:\/\/mypa.gatheomix.com\/en\/wp-json\/wp\/v2\/pages\/300\/revisions\/983"}],"wp:attachment":[{"href":"https:\/\/mypa.gatheomix.com\/en\/wp-json\/wp\/v2\/media?parent=300"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}